{"id":625,"date":"2017-08-18T17:51:51","date_gmt":"2017-08-18T15:51:51","guid":{"rendered":"http:\/\/gpflug.de\/website\/?p=625"},"modified":"2018-05-25T14:08:51","modified_gmt":"2018-05-25T12:08:51","slug":"da-sein","status":"publish","type":"post","link":"https:\/\/gpflug.de\/website\/2017\/08\/18\/da-sein\/","title":{"rendered":"Da sein"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-758\" src=\"https:\/\/gpflug.de\/website\/wp-content\/uploads\/2017\/08\/IMG_20171103_140934-EFFECTS-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/gpflug.de\/website\/wp-content\/uploads\/2017\/08\/IMG_20171103_140934-EFFECTS-300x225.jpg 300w, https:\/\/gpflug.de\/website\/wp-content\/uploads\/2017\/08\/IMG_20171103_140934-EFFECTS-768x576.jpg 768w, https:\/\/gpflug.de\/website\/wp-content\/uploads\/2017\/08\/IMG_20171103_140934-EFFECTS-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Morgens,<\/p>\n<p>Wenn die Welt noch frisch ist,<\/p>\n<p>Und das Blau des Himmels klingt<\/p>\n<p>Kommen die Schwalben<\/p>\n<p>\u00fcber den Teich geflogen<\/p>\n<p>und trinken ein Schn\u00e4belchen<\/p>\n<p>Wasser.<\/p>\n ","protected":false},"excerpt":{"rendered":"<p>Morgens, Wenn die Welt noch frisch ist, Und das Blau des Himmels klingt Kommen die Schwalben \u00fcber den Teich geflogen und trinken ein Schn\u00e4belchen Wasser.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"slim_seo":{"title":"Da sein - Yoga Life Gerhard Pflug","description":"Morgens, Wenn die Welt noch frisch ist, Und das Blau des Himmels klingt Kommen die Schwalben \u00fcber den Teich geflogen und trinken ein Schn\u00e4belchen Wasser."},"_slim_seo_primary_term_category":0,"_slim_seo_primary_term_post_tag":0,"footnotes":""},"categories":[1,6],"tags":[],"class_list":["post-625","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-kategorie-2"],"_links":{"self":[{"href":"https:\/\/gpflug.de\/website\/wp-json\/wp\/v2\/posts\/625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpflug.de\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gpflug.de\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gpflug.de\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gpflug.de\/website\/wp-json\/wp\/v2\/comments?post=625"}],"version-history":[{"count":5,"href":"https:\/\/gpflug.de\/website\/wp-json\/wp\/v2\/posts\/625\/revisions"}],"predecessor-version":[{"id":759,"href":"https:\/\/gpflug.de\/website\/wp-json\/wp\/v2\/posts\/625\/revisions\/759"}],"wp:attachment":[{"href":"https:\/\/gpflug.de\/website\/wp-json\/wp\/v2\/media?parent=625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gpflug.de\/website\/wp-json\/wp\/v2\/categories?post=625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gpflug.de\/website\/wp-json\/wp\/v2\/tags?post=625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}